{"id":3898,"count":21,"description":"","link":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/","name":"Bloques","slug":"bloques","taxonomy":"product_cat","parent":2047,"meta":[],"menu_order":24,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olive Wood Blocks Holy Land Olive Wood - Bethlehem Olive Wood Factory<\/title>\n<meta name=\"description\" content=\"Bethlehem olive wood handicrafts(i.e.rosaries,kitchenware,nativity,sets,beads)pen-blanks carvings,slabs,blocks,&amp;raw stock in standard and custom dimensions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olive Wood Blocks Holy Land Olive Wood - Bethlehem Olive Wood Factory\" \/>\n<meta property=\"og:description\" content=\"Bethlehem olive wood handicrafts(i.e.rosaries,kitchenware,nativity,sets,beads)pen-blanks carvings,slabs,blocks,&amp;raw stock in standard and custom dimensions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/\" \/>\n<meta property=\"og:site_name\" content=\"Holy Land Olive Wood - Bethlehem Olive Wood Factory\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/categoria-producto\\\/madera-de-olivo\\\/bloques\\\/\",\"url\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/categoria-producto\\\/madera-de-olivo\\\/bloques\\\/\",\"name\":\"Olive Wood Blocks Holy Land Olive Wood - Bethlehem Olive Wood Factory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/#website\"},\"description\":\"Bethlehem olive wood handicrafts(i.e.rosaries,kitchenware,nativity,sets,beads)pen-blanks carvings,slabs,blocks,&raw stock in standard and custom dimensions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/categoria-producto\\\/madera-de-olivo\\\/bloques\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/categoria-producto\\\/madera-de-olivo\\\/bloques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madera de olivo\",\"item\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/categoria-producto\\\/madera-de-olivo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bloques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/\",\"name\":\"Holy Land Olive Wood - Bethlehem Olive Wood Factory\",\"description\":\"Holy Land Olivewood Bethlehem\",\"publisher\":{\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/#organization\",\"name\":\"Holy Land Olivewood\",\"url\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Holy Land Olivewood\"},\"image\":{\"@id\":\"https:\\\/\\\/holyland-olivewood.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/holylandolivewood.bethlehem\\\/\",\"http:\\\/\\\/instagram.com\\\/holy.land.olive.wood\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olive Wood Blocks Holy Land Olive Wood - Bethlehem Olive Wood Factory","description":"Bethlehem olive wood handicrafts(i.e.rosaries,kitchenware,nativity,sets,beads)pen-blanks carvings,slabs,blocks,&raw stock in standard and custom dimensions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/","og_locale":"es_ES","og_type":"article","og_title":"Olive Wood Blocks Holy Land Olive Wood - Bethlehem Olive Wood Factory","og_description":"Bethlehem olive wood handicrafts(i.e.rosaries,kitchenware,nativity,sets,beads)pen-blanks carvings,slabs,blocks,&raw stock in standard and custom dimensions.","og_url":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/","og_site_name":"Holy Land Olive Wood - Bethlehem Olive Wood Factory","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/","url":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/","name":"Olive Wood Blocks Holy Land Olive Wood - Bethlehem Olive Wood Factory","isPartOf":{"@id":"https:\/\/holyland-olivewood.com\/es\/#website"},"description":"Bethlehem olive wood handicrafts(i.e.rosaries,kitchenware,nativity,sets,beads)pen-blanks carvings,slabs,blocks,&raw stock in standard and custom dimensions.","breadcrumb":{"@id":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/bloques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/holyland-olivewood.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Madera de olivo","item":"https:\/\/holyland-olivewood.com\/es\/categoria-producto\/madera-de-olivo\/"},{"@type":"ListItem","position":3,"name":"Bloques"}]},{"@type":"WebSite","@id":"https:\/\/holyland-olivewood.com\/es\/#website","url":"https:\/\/holyland-olivewood.com\/es\/","name":"Holy Land Olive Wood - Bethlehem Olive Wood Factory","description":"Holy Land Olivewood Bethlehem","publisher":{"@id":"https:\/\/holyland-olivewood.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holyland-olivewood.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/holyland-olivewood.com\/es\/#organization","name":"Holy Land Olivewood","url":"https:\/\/holyland-olivewood.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/holyland-olivewood.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Holy Land Olivewood"},"image":{"@id":"https:\/\/holyland-olivewood.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/holylandolivewood.bethlehem\/","http:\/\/instagram.com\/holy.land.olive.wood"]}]}},"_links":{"self":[{"href":"https:\/\/holyland-olivewood.com\/es\/wp-json\/wp\/v2\/product_cat\/3898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holyland-olivewood.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/holyland-olivewood.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/holyland-olivewood.com\/es\/wp-json\/wp\/v2\/product_cat\/2047"}],"wp:post_type":[{"href":"https:\/\/holyland-olivewood.com\/es\/wp-json\/wp\/v2\/product?product_cat=3898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}